{"id":3885,"count":1,"description":"","link":"https:\/\/chernigiv.name\/uk\/tag\/prytoka","name":"\u043f\u0440\u0438\u0442\u043e\u043a\u0430","slug":"prytoka","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/chernigiv.name\/uk\/wp-json\/wp\/v2\/tags\/3885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chernigiv.name\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chernigiv.name\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chernigiv.name\/uk\/wp-json\/wp\/v2\/posts?tags=3885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}